{"id":17627,"date":"2022-07-15T11:47:44","date_gmt":"2022-07-15T15:47:44","guid":{"rendered":"https:\/\/www.doyonavocats.ca\/?p=17627"},"modified":"2022-07-15T11:47:44","modified_gmt":"2022-07-15T15:47:44","slug":"sil-nappartient-pas-au-judiciaire-de-dicter-aux-autorites-la-facon-dont-elles-doivent-proceder-afin-de-respecter-les-volontes-du-legislateur-il-nen-demeure-pas-moins-que-la","status":"publish","type":"post","link":"https:\/\/www.doyonavocats.ca\/en\/sil-nappartient-pas-au-judiciaire-de-dicter-aux-autorites-la-facon-dont-elles-doivent-proceder-afin-de-respecter-les-volontes-du-legislateur-il-nen-demeure-pas-moins-que-la\/","title":{"rendered":"S\u2019il n\u2019appartient pas au judiciaire de dicter aux autorit\u00e9s la fa\u00e7on dont elles doivent proc\u00e9der afin de respecter les volont\u00e9s du l\u00e9gislateur, il n\u2019en demeure pas moins que la d\u00e9nonciation d\u2019une violation constitutionnelle rel\u00e8ve de la mission des tribunaux : Martinbeault c. R., 2022 QCCA 902"},"content":{"rendered":"<p data-viibes-parag=\"9\" data-viibes-start=\"8\" data-viibes-end=\"7\"><a href=\"https:\/\/canlii.ca\/t\/jpwvx\">Martinbeault c. R., 2022 QCCA 902<\/a><\/p>\n<h2 style=\"text-align: justify;\" data-viibes-parag=\"9\" data-viibes-start=\"8\" data-viibes-end=\"7\"><strong>Malgr\u00e9 l&#8217;importance et la fiabilit\u00e9 des \u00e9l\u00e9ments saisis, la gravit\u00e9 des violations des droits garantis par la <i><a class=\"reflex2-link\" href=\"https:\/\/www.canlii.org\/fr\/ca\/legis\/lois\/annexe-b-de-la-loi-de-1982-sur-le-canada-r-u-1982-c-11\/derniere\/annexe-b-de-la-loi-de-1982-sur-le-canada-r-u-1982-c-11.html\">Charte<\/a><\/i>, l&#8217;incidence de telles violations et le risque r\u00e9el que de telles violations se r\u00e9p\u00e8tent, pour des raisons d\u2019ordre administratif au surplus, justifient d&#8217;exclure la preuve.<\/strong><\/h2>\n<p style=\"text-align: justify;\" data-viibes-parag=\"9\" data-viibes-start=\"8\" data-viibes-end=\"7\">[9] Le juge de premi\u00e8re instance rejette la requ\u00eate s\u00e9ance tenante et conclut que l\u2019arrestation et les fouilles accessoires ne contreviennent pas aux droits du requ\u00e9rant. La d\u00e9tention \u00e9tait justifi\u00e9e dans la mesure o\u00f9 il n\u2019\u00e9tait pas possible pour le requ\u00e9rant de payer l\u2019amende due ou de signer un engagement \u00e0 compara\u00eetre sur place. <strong>Le juge estime qu\u2019il ne lui revient pas d\u2019ordonner \u00e0 la branche ex\u00e9cutive du gouvernement d\u2019engager des frais pour munir les v\u00e9hicules de patrouille de l\u2019\u00e9quipement n\u00e9cessaire \u00e0 l\u2019ex\u00e9cution d\u2019un mandat percepteur<\/strong>. Dans ces circonstances, la d\u00e9tention du requ\u00e9rant pour le temps requis afin d\u2019assurer son transport au Centre de d\u00e9tention n\u2019est pas d\u00e9raisonnable, et les policiers \u00e9taient justifi\u00e9s de proc\u00e9der \u00e0 une fouille par palpation pour des motifs de s\u00e9curit\u00e9. Il rejette donc la requ\u00eate en exclusion de la preuve en concluant qu\u2019il n\u2019y a pas eu d\u2019atteinte aux droits fondamentaux du requ\u00e9rant. Compte tenu de cette conclusion, le juge ne proc\u00e8de pas \u00e0 l\u2019analyse sous l\u2019article 24 (2) de la <em>Charte<\/em><a href=\"https:\/\/www.canlii.org\/fr\/qc\/qcca\/doc\/2022\/2022qcca902\/2022qcca902.html#_ftn4\" name=\"_ftnref4\">[4]<\/a>.<\/p>\n<p data-viibes-parag=\"9\" data-viibes-start=\"8\" data-viibes-end=\"7\">&#8230;<\/p>\n<div class=\"paragWrapper\">\n<p class=\"Paragraphe\" style=\"text-align: justify;\" data-viibes-parag=\"14\" data-viibes-start=\"13\" data-viibes-end=\"12\">[<a class=\"reflex-paragAnchor\" name=\"par14\"><\/a>14] En appel, l&#8217;intim\u00e9e conc\u00e8de, \u00e0 juste titre, que le juge de premi\u00e8re instance commet une erreur de droit en concluant \u00e0 l&#8217;absence de violation. La m\u00e9connaissance par les policiers du cadre l\u00e9gislatif pr\u00e9vu aux <a class=\"reflex2-link\" href=\"https:\/\/www.canlii.org\/fr\/qc\/legis\/lois\/rlrq-c-c-25.1\/derniere\/rlrq-c-c-25.1.html#art324_smooth\">articles 324<\/a> et<a class=\"reflex2-link\" href=\"https:\/\/www.canlii.org\/fr\/qc\/legis\/lois\/rlrq-c-c-25.1\/derniere\/rlrq-c-c-25.1.html#art325_smooth\"> 325<\/a><i><a class=\"reflex2-link\" href=\"https:\/\/www.canlii.org\/fr\/qc\/legis\/lois\/rlrq-c-c-25.1\/derniere\/rlrq-c-c-25.1.html\">C.p.p.<\/a><\/i> et le fait qu&#8217;ils estiment \u00eatre dans l&#8217;obligation d&#8217;arr\u00eater une personne vis\u00e9e par un mandat percepteur afin de l&#8217;amener au Centre de d\u00e9tention plut\u00f4t que de le lib\u00e9rer sur simple engagement de compara\u00eetre est probl\u00e9matique. Cette question sera abord\u00e9e plus en d\u00e9tail dans le cadre de l\u2019analyse de l\u2019admissibilit\u00e9 de la preuve. Retenons que la d\u00e9tention du requ\u00e9rant dans les circonstances outrepasse le cadre l\u00e9gislatif pr\u00e9vu \u00e0 l&#8217;<a class=\"reflex2-link\" href=\"https:\/\/www.canlii.org\/fr\/qc\/legis\/lois\/rlrq-c-c-25.1\/derniere\/rlrq-c-c-25.1.html#art324_smooth\">article 324<\/a> <i><a class=\"reflex2-link\" href=\"https:\/\/www.canlii.org\/fr\/qc\/legis\/lois\/rlrq-c-c-25.1\/derniere\/rlrq-c-c-25.1.html\">C.p.p<\/a><\/i> et constitue une violation de l\u2019article 9 de la <i>Charte<\/i>.<\/p>\n<\/div>\n<div class=\"paragWrapper\">\n<p class=\"Paragraphe\" style=\"text-align: justify;\" data-viibes-parag=\"15\" data-viibes-start=\"14\" data-viibes-end=\"13\">[<a class=\"reflex-paragAnchor\" name=\"par15\"><\/a>15] L&#8217;intim\u00e9e reconna\u00eet par le fait m\u00eame le caract\u00e8re abusif de la fouille par palpation qui d\u00e9coule de la d\u00e9tention initiale. Elle ajoute cependant que, n&#8217;e\u00fbt \u00e9t\u00e9 l&#8217;ill\u00e9galit\u00e9 de la d\u00e9tention, le policier \u00e9tait justifi\u00e9, pour des raisons de s\u00e9curit\u00e9, de proc\u00e9der \u00e0 une telle fouille avant d&#8217;installer le requ\u00e9rant dans le v\u00e9hicule de patrouille aux fins de transport vers le Centre de d\u00e9tention.<\/p>\n<div class=\"paragWrapper\">\n<p class=\"Paragraphe\" style=\"text-align: justify;\" data-viibes-parag=\"16\" data-viibes-start=\"15\" data-viibes-end=\"14\">[16] En somme, comme conc\u00e9d\u00e9 par l&#8217;intim\u00e9e, et pour les motifs qui seront plus amplement d\u00e9taill\u00e9s dans le cadre de l&#8217;examen de la gravit\u00e9 des violations, la Cour conclut que le juge a commis une erreur r\u00e9visable en concluant \u00e0 l&#8217;absence de violation des droits constitutionnels du requ\u00e9rant.<\/p>\n<p data-viibes-parag=\"20\" data-viibes-start=\"19\" data-viibes-end=\"18\">&#8230;<\/p>\n<p style=\"text-align: justify;\" data-viibes-parag=\"25\" data-viibes-start=\"24\" data-viibes-end=\"23\">[25]\u00a0\u00a0 \u00a0\u00a0 Le requ\u00e9rant est intercept\u00e9 en raison d&#8217;une contravention au <em>Code de la s\u00e9curit\u00e9 routi\u00e8re<\/em>. Une v\u00e9rification au CRPQ r\u00e9v\u00e8le ensuite qu&#8217;il fait l&#8217;objet d&#8217;un mandat percepteur d\u00e9livr\u00e9 par la Ville de Montr\u00e9al pour une amende impay\u00e9e.<\/p>\n<p style=\"text-align: justify;\" data-viibes-parag=\"26\" data-viibes-start=\"25\" data-viibes-end=\"24\">[26]\u00a0\u00a0 \u00a0\u00a0 Les policiers proc\u00e8dent \u00e0 son arrestation. Le requ\u00e9rant ne peut cependant \u00eatre conduit imm\u00e9diatement devant le percepteur des amendes puisque l&#8217;intervention se d\u00e9roule un samedi.<\/p>\n<p style=\"text-align: justify;\" data-viibes-parag=\"27\" data-viibes-start=\"26\" data-viibes-end=\"25\">[27]\u00a0\u00a0 \u00a0\u00a0 Selon les principes \u00e9nonc\u00e9s aux <a href=\"https:\/\/www.canlii.org\/fr\/qc\/legis\/lois\/rlrq-c-c-25.1\/derniere\/rlrq-c-c-25.1.html#art324_smooth\">articles 324<\/a> et<a href=\"https:\/\/www.canlii.org\/fr\/qc\/legis\/lois\/rlrq-c-c-25.1\/derniere\/rlrq-c-c-25.1.html#art325_smooth\"> 325<\/a> du <em><a href=\"https:\/\/www.canlii.org\/fr\/qc\/legis\/lois\/rlrq-c-c-25.1\/derniere\/rlrq-c-c-25.1.html\">C.p.p.<\/a>,<\/em> sa d\u00e9tention aurait d\u00fb \u00eatre de courte dur\u00e9e. En effet, ces articles pr\u00e9voient\u00a0:<\/p>\n<table style=\"font-weight: 400;\">\n<tbody>\n<tr>\n<td width=\"288\"><strong>324.<\/strong> Lorsque le d\u00e9fendeur est introuvable et qu\u2019il n\u2019a pas pay\u00e9 les sommes dues, le percepteur peut demander \u00e0 un juge de d\u00e9cerner un mandat d\u2019amener le d\u00e9fendeur devant le percepteur afin que celui-ci puisse recouvrer ces sommes conform\u00e9ment au pr\u00e9sent chapitre.<\/p>\n<p>&nbsp;<\/p>\n<p><u>Toutefois, lorsque le d\u00e9fendeur ne peut \u00eatre conduit imm\u00e9diatement devant le percepteur, celui qui proc\u00e8de \u00e0 l\u2019arrestation met le d\u00e9fendeur en libert\u00e9 pourvu que celui-ci lui d\u00e9clare son adresse, lui fournisse, si n\u00e9cessaire, les renseignements permettant d\u2019en confirmer l\u2019exactitude et s\u2019engage \u00e0 se pr\u00e9senter devant le percepteur \u00e0 la date indiqu\u00e9e sur l\u2019engagement<\/u>; lorsque le d\u00e9fendeur refuse de se conformer \u00e0 ces exigences, il est conduit devant le juge qui a d\u00e9cern\u00e9 le mandat ou un juge ayant comp\u00e9tence pour le faire dans le m\u00eame district ou devant un juge ayant comp\u00e9tence dans le district o\u00f9 le mandat a \u00e9t\u00e9 ex\u00e9cut\u00e9. Si le d\u00e9fendeur persiste dans son refus, le juge lui impose une peine d\u2019emprisonnement et d\u00e9livre un mandat d\u2019emprisonnement pour d\u00e9faut de paiement des sommes dues.<\/p>\n<p>&nbsp;<\/td>\n<td width=\"288\"><strong>\u00a0<\/strong><strong>324<\/strong>. Where the defendant cannot be found and where he did not pay the sums due, the collector may, in order to recover the sums in accordance with this chapter, apply to the judge to issue a warrant to bring a defendant before the collector.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><u>Where the defendant cannot be brought forthwith before the collector, the person who arrested him shall release him from custody providing he gives his address or, if necessary, any information confirming the accuracy thereof, and undertakes to appear before the collector on the day specified in the recognizance<\/u>; where the defendant refuses to comply with these requirements, he shall be brought before the judge who issued the warrant or a judge having jurisdiction to issue such a warrant within the same judicial district or before a judge having jurisdiction in the judicial district where the warrant was executed. Where the defendant persists in his refusal, the judge shall order his imprisonment and issue a warrant of committal in default of payment of the sums due.<\/p>\n<p>&nbsp;<\/td>\n<\/tr>\n<tr>\n<td width=\"288\"><strong>325.<\/strong>\u00a0<u>Le d\u00e9fendeur peut payer tout ou partie des sommes dues \u00e0 la personne charg\u00e9e de l\u2019ex\u00e9cution du mandat d\u2019amener. Celle-ci doit remettre au d\u00e9fendeur un re\u00e7u attestant le paiement et verser le montant pay\u00e9 au percepteur.<\/u><\/p>\n<p><u>\u00a0<\/u><\/p>\n<p><u>Le paiement de la totalit\u00e9 des sommes dues suspend l\u2019ex\u00e9cution du mandat<\/u>.<\/p>\n<p>&nbsp;<\/td>\n<td width=\"288\"><strong>325.<\/strong> <u>The defendant may pay the sums due in whole or in part to the person entrusted with the execution of the warrant to bring a defendant. Such person shall give a receipt to the defendant as evidence of payment and remit the amount paid to the collector.<\/u><\/p>\n<p><u>\u00a0<\/u><\/p>\n<p><u>Payment of the total amount due suspends execution of the warrant<\/u>.<\/p>\n<p><u>\u00a0<\/u><\/p>\n<p><u>[Soulignements ajout\u00e9s]<\/u><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\" data-viibes-parag=\"28\" data-viibes-start=\"27\" data-viibes-end=\"26\">[28]\u00a0\u00a0 \u00a0\u00a0 L&#8217;objectif poursuivi par le l\u00e9gislateur est de s&#8217;assurer que la personne faisant l&#8217;objet d&#8217;un mandat percepteur puisse \u00eatre mise en libert\u00e9 sans d\u00e9lai si elle ne peut \u00eatre conduite imm\u00e9diatement devant le percepteur des amendes ou payer les sommes dues. La mise en libert\u00e9 exige simplement que la personne d\u00e9clare son adresse, fournisse les renseignements confirmant l&#8217;exactitude de cette information et signe un engagement \u00e0 compara\u00eetre devant le percepteur des amendes \u00e0 la date indiqu\u00e9e. Cette option pr\u00e9vue par le l\u00e9gislateur n\u2019a pas \u00e9t\u00e9 offerte au requ\u00e9rant.<\/p>\n<p style=\"text-align: justify;\" data-viibes-parag=\"29\" data-viibes-start=\"28\" data-viibes-end=\"27\">[29]\u00a0\u00a0 \u00a0\u00a0 La preuve d\u00e9montre pourtant que le requ\u00e9rant collabore avec les policiers. Il n&#8217;est pas agressif. Il s&#8217;identifie, fournit son adresse et des pi\u00e8ces d&#8217;identit\u00e9 confirmant celle-ci. Les policiers estiment cependant ne pas \u00eatre en mesure de le mettre en libert\u00e9, car ils sont incapables de v\u00e9rifier le mandat, de lui pr\u00e9ciser la nature de l&#8217;amende impay\u00e9e et le montant de celle\u2011ci. Ils ne peuvent donc lui offrir de payer ce montant et ils ne disposent pas de l&#8217;\u00e9quipement requis pour recevoir le paiement. Ils ne sont pas non plus en mesure de lui faire signer un engagement \u00e0 compara\u00eetre.<\/p>\n<p style=\"text-align: justify;\" data-viibes-parag=\"30\" data-viibes-start=\"29\" data-viibes-end=\"28\">[30]\u00a0\u00a0 \u00a0\u00a0 La preuve administr\u00e9e r\u00e9v\u00e8le que si l&#8217;interception \u00e9tait survenue un jour de semaine, les policiers auraient pu faire appel \u00e0 une unit\u00e9 mobile qui serait venue sur place pour compl\u00e9ter les \u00e9tapes administratives requises afin de lib\u00e9rer le requ\u00e9rant.<strong> Cette unit\u00e9 n&#8217;est toutefois pas disponible la fin de semaine<\/strong>.<\/p>\n<p style=\"text-align: justify;\" data-viibes-parag=\"31\" data-viibes-start=\"30\" data-viibes-end=\"29\">[31]\u00a0\u00a0 \u00a0\u00a0 Au surplus, le policier confirme, lors de son t\u00e9moignage sur le voir-dire, ne pas \u00eatre familier avec les principes \u00e9nonc\u00e9s aux <a href=\"https:\/\/www.canlii.org\/fr\/qc\/legis\/lois\/rlrq-c-c-25.1\/derniere\/rlrq-c-c-25.1.html#art324_smooth\">articles 324<\/a> et<a href=\"https:\/\/www.canlii.org\/fr\/qc\/legis\/lois\/rlrq-c-c-25.1\/derniere\/rlrq-c-c-25.1.html#art325_smooth\"> 325<\/a> <em><a href=\"https:\/\/www.canlii.org\/fr\/qc\/legis\/lois\/rlrq-c-c-25.1\/derniere\/rlrq-c-c-25.1.html\">C.p.p<\/a><\/em><a href=\"https:\/\/www.canlii.org\/fr\/qc\/legis\/lois\/rlrq-c-c-25.1\/derniere\/rlrq-c-c-25.1.html\">.<\/a>, de sorte qu\u2019il n&#8217;envisage aucune des alternatives qu\u2019ils pr\u00e9voient pour \u00e9viter au justiciable une d\u00e9tention ind\u00fbment prolong\u00e9e. Pour lui, la seule avenue possible consiste \u00e0 amener le requ\u00e9rant au Centre de d\u00e9tention, ce qui implique de prolonger, de fa\u00e7on importante, la dur\u00e9e de la d\u00e9tention.<\/p>\n<div class=\"paragWrapper\">\n<p class=\"Paragraphe\" style=\"text-align: justify;\" data-viibes-parag=\"32\" data-viibes-start=\"31\" data-viibes-end=\"30\">[<a class=\"reflex-paragAnchor\" name=\"par32\"><\/a>32]\u00a0\u00a0 \u00a0\u00a0 Le juge de premi\u00e8re instance conclut\u00a0:<\/p>\n<\/div>\n<p class=\"Citationenretrait\" style=\"text-align: justify; padding-left: 40px;\">Donc, en l\u2019esp\u00e8ce, le Tribunal retient de la preuve que dans l\u2019esprit du policier, celui-ci allait de toute fa\u00e7on et en tout \u00e9tat de cause d\u00e9tenir dans le v\u00e9hicule policier le requ\u00e9rant. Et donc, la suite de l\u2019intervention, que le policier ait pens\u00e9 ou non au fourgon pour venir payer ou pas, change peu de choses.<\/p>\n<p class=\"Citationenretrait\" style=\"text-align: justify; padding-left: 40px;\">Maintenant, <strong>le Tribunal consid\u00e8re qu\u2019il n\u2019est pas l\u00e0 pour imposer ou pour constater des violations en important comme contrepartie aux autorit\u00e9s publiques l\u2019obligation de fournir du mat\u00e9riel sp\u00e9cifique en l\u2019esp\u00e8ce, du mat\u00e9riel pour produire des engagements ou pour permettre le paiement dans les v\u00e9hicules de patrouille<\/strong>.<\/p>\n<p class=\"Citationenretrait\" style=\"text-align: justify; padding-left: 40px;\"><strong>Il n\u2019appartient pas au judiciaire d\u2019imposer \u00e0 l\u2019ex\u00e9cutif ce genre de d\u00e9penses ou encore de d\u00e9cr\u00e9ter des violations si les autorit\u00e9s municipales en l\u2019esp\u00e8ce choisissent de pas \u00e9quiper les v\u00e9hicules de police de ce genre de facilit\u00e9s<\/strong>.<\/p>\n<div class=\"paragWrapper\">\n<p class=\"Paragraphe\" style=\"text-align: justify;\" data-viibes-parag=\"33\" data-viibes-start=\"32\" data-viibes-end=\"31\">[<a class=\"reflex-paragAnchor\" name=\"par33\"><\/a>33]\u00a0\u00a0 \u00a0\u00a0 Or, s\u2019il n\u2019appartient pas au judiciaire de dicter aux autorit\u00e9s municipales la fa\u00e7on dont elles doivent proc\u00e9der afin de respecter les volont\u00e9s du l\u00e9gislateur, il n\u2019en demeure pas moins que le <i><a class=\"reflex2-link\" href=\"https:\/\/www.canlii.org\/fr\/qc\/legis\/lois\/rlrq-c-c-25.1\/derniere\/rlrq-c-c-25.1.html\">C.p.p<\/a><\/i><a class=\"reflex2-link\" href=\"https:\/\/www.canlii.org\/fr\/qc\/legis\/lois\/rlrq-c-c-25.1\/derniere\/rlrq-c-c-25.1.html\">.<\/a> pr\u00e9voit qu\u2019une personne faisant l\u2019objet d\u2019un mandat percepteur doit \u00eatre mise en libert\u00e9 sans d\u00e9lai. Une v\u00e9rification t\u00e9l\u00e9phonique du mandat et un simple formulaire d\u2019engagement \u00e0 compara\u00eetre auraient permis de satisfaire \u00e0 cet objectif.\u00a0 Le fait que les policiers estiment n\u2019avoir d\u2019autre choix que de d\u00e9tenir le requ\u00e9rant entraine une violation grave de ses droits et la d\u00e9nonciation d\u2019une telle violation <strong>rel\u00e8ve de la mission des tribunaux<\/strong>.<\/p>\n<\/div>\n<div class=\"paragWrapper\">\n<p class=\"Paragraphe\" style=\"text-align: justify;\" data-viibes-parag=\"34\" data-viibes-start=\"33\" data-viibes-end=\"32\">[<a class=\"reflex-paragAnchor\" name=\"par34\"><\/a>34]\u00a0\u00a0 \u00a0\u00a0 Cette violation est d&#8217;autant plus importante lorsqu&#8217;elle a pour cons\u00e9quence, comme c&#8217;est le cas ici, de soumettre automatiquement la personne d\u00e9tenue \u00e0 une fouille par palpation. En effet, lors de son t\u00e9moignage, le policier explique qu\u2019avant d\u2019asseoir le requ\u00e9rant dans son v\u00e9hicule pour l\u2019amener au Centre de d\u00e9tention, il proc\u00e8de par prudence, comme il le fait syst\u00e9matiquement, \u00e0 une fouille par palpation.<\/p>\n<\/div>\n<div class=\"paragWrapper\">\n<p class=\"Paragraphe\" style=\"text-align: justify;\" data-viibes-parag=\"35\" data-viibes-start=\"34\" data-viibes-end=\"33\">[<a class=\"reflex-paragAnchor\" name=\"par35\"><\/a>35]\u00a0\u00a0 \u00a0\u00a0 L\u2019ill\u00e9galit\u00e9 de la d\u00e9tention emporte celle des fouilles qui s\u2019en sont suivies. Ces fouilles, ainsi que la seconde arrestation qui s\u2019en est suivie, sont ici inextricablement li\u00e9es \u00e0 la d\u00e9tention initiale. Cela \u00e9tant, le fait que le requ\u00e9rant soit assujetti \u00e0 une telle fouille syst\u00e9matique, alors que sa pr\u00e9sence dans le v\u00e9hicule de police se justifie uniquement par l&#8217;incapacit\u00e9 pour les policiers de respecter les exigences du <i><a class=\"reflex2-link\" href=\"https:\/\/www.canlii.org\/fr\/qc\/legis\/lois\/rlrq-c-c-25.1\/derniere\/rlrq-c-c-25.1.html\">C.p.p.<\/a><\/i>, ajoute \u00e0 la gravit\u00e9 de la violation initiale et favorise l\u2019exclusion de la preuve.<\/p>\n<p data-viibes-parag=\"35\" data-viibes-start=\"34\" data-viibes-end=\"33\">&#8230;<\/p>\n<p style=\"text-align: justify;\" data-viibes-parag=\"38\" data-viibes-start=\"37\" data-viibes-end=\"36\">[38] Ces arguments ne peuvent \u00eatre retenus. Si la d\u00e9tention du requ\u00e9rant sur le bord de la route en attendant la signature d&#8217;un engagement de compara\u00eetre aurait pu \u00eatre consid\u00e9r\u00e9e comme \u00e9tant de courte dur\u00e9e, <strong>il en va autrement \u00e0 partir du moment o\u00f9 son transport au Centre de d\u00e9tention est requis en raison de contraintes administratives<\/strong>. Tel que le rappelle la Cour supr\u00eame dans <em>Harrison<\/em><a href=\"https:\/\/www.canlii.org\/fr\/qc\/qcca\/doc\/2022\/2022qcca902\/2022qcca902.html#_ftn14\" name=\"_ftnref14\">[14]<\/a>, le fait pour un automobiliste d&#8217;\u00eatre arr\u00eat\u00e9 et fouill\u00e9 par un policier a \u00ab\u00a0une incidence plus qu&#8217;anodine sur ses attentes l\u00e9gitimes en mati\u00e8re de libert\u00e9 et de vie priv\u00e9e\u00a0\u00bb.<\/p>\n<p data-viibes-parag=\"38\" data-viibes-start=\"37\" data-viibes-end=\"36\">&#8230;<\/p>\n<div class=\"paragWrapper\">\n<p class=\"Paragraphe\" style=\"text-align: justify;\" data-viibes-parag=\"47\" data-viibes-start=\"46\" data-viibes-end=\"45\">[<a class=\"reflex-paragAnchor\" name=\"par47\"><\/a>47] Les violations reproch\u00e9es, qui d\u00e9coulent de la m\u00e9connaissance par les policiers de dispositions l\u00e9gales \u00e9l\u00e9mentaires encadrant l\u2019exercice de leurs pouvoirs en l\u2019esp\u00e8ce <strong>et de leur incapacit\u00e9<\/strong> \u00e0 mettre rapidement en libert\u00e9 un citoyen faisant l&#8217;objet d&#8217;un mandat percepteur, et ce, contrairement aux exigences du <i><a class=\"reflex2-link\" href=\"https:\/\/www.canlii.org\/fr\/qc\/legis\/lois\/rlrq-c-c-25.1\/derniere\/rlrq-c-c-25.1.html\">Code de proc\u00e9dure p\u00e9nale<\/a><\/i>, doivent \u00eatre d\u00e9nonc\u00e9es clairement, au risque, dans le cas contraire, qu\u2019elles se r\u00e9p\u00e8tent.<\/p>\n<\/div>\n<div class=\"paragWrapper\" style=\"text-align: justify;\">\n<p class=\"Paragraphe\" data-viibes-parag=\"48\" data-viibes-start=\"47\" data-viibes-end=\"46\">[<a class=\"reflex-paragAnchor\" name=\"par48\"><\/a>48] D\u2019autant plus qu\u2019un mandat percepteur est susceptible d\u2019\u00eatre lanc\u00e9 dans une multitude de circonstances, incluant, comme c&#8217;est le cas en l&#8217;esp\u00e8ce, l&#8217;omission de payer une amende pour avoir promen\u00e9 un chien sans laisse. Tout citoyen risque de faire l&#8217;objet d&#8217;un tel mandat, que ce soit parce qu&#8217;il n&#8217;a pas re\u00e7u le constat d&#8217;infraction ou qu&#8217;il a oubli\u00e9 de le payer.<\/p>\n<\/div>\n<div class=\"paragWrapper\">\n<p class=\"Paragraphe\" style=\"text-align: justify;\" data-viibes-parag=\"49\" data-viibes-start=\"48\" data-viibes-end=\"47\">[<a class=\"reflex-paragAnchor\" name=\"par49\"><\/a>49] Il appara\u00eet contraire \u00e0 une saine administration de la justice qu&#8217;une personne plac\u00e9e dans les m\u00eames circonstances que celles du requ\u00e9rant soit priv\u00e9e, <strong>pour des raisons administratives<\/strong>, de la possibilit\u00e9 de signer un engagement \u00e0 compara\u00eetre et de son droit de payer l&#8217;amende et, ultimement, de sa libert\u00e9. Une personne raisonnable s&#8217;insurgerait en r\u00e9alisant qu&#8217;elle s&#8217;expose \u00e0 ce qu&#8217;une br\u00e8ve d\u00e9tention sur le bord de la route se transforme, dans ce contexte, en une arrestation avec transport au Centre de d\u00e9tention et qu&#8217;elle doive, au surplus, se soumettre une fouille par palpation. Au-del\u00e0 de la perte de temps, de l&#8217;humiliation, de l&#8217;incertitude g\u00e9n\u00e9r\u00e9e par cette proc\u00e9dure, un constat s&#8217;impose\u00a0: le citoyen qui omet de payer une amende se trouverait assujetti aux m\u00eames inconv\u00e9nients qu\u2019une personne arr\u00eat\u00e9e pour une infraction plus s\u00e9rieuse. Or, telle n\u2019est clairement pas la volont\u00e9 que le l\u00e9gislateur a exprim\u00e9e aux <a class=\"reflex2-link\" href=\"https:\/\/www.canlii.org\/fr\/qc\/legis\/lois\/rlrq-c-c-25.1\/derniere\/rlrq-c-c-25.1.html#art324_smooth\">articles 324<\/a> et<a class=\"reflex2-link\" href=\"https:\/\/www.canlii.org\/fr\/qc\/legis\/lois\/rlrq-c-c-25.1\/derniere\/rlrq-c-c-25.1.html#art325_smooth\"> 325<\/a> <i><a class=\"reflex2-link\" href=\"https:\/\/www.canlii.org\/fr\/qc\/legis\/lois\/rlrq-c-c-25.1\/derniere\/rlrq-c-c-25.1.html\">C.p.p.<\/a>, <\/i>lesquels pr\u00e9voient au contraire des modalit\u00e9s pour assurer que la d\u00e9tention soit la plus courte possible.<\/p>\n<div class=\"paragWrapper\" style=\"text-align: justify;\">\n<p class=\"Paragraphe\" data-viibes-parag=\"50\" data-viibes-start=\"49\" data-viibes-end=\"48\">[<a class=\"reflex-paragAnchor\" name=\"par50\"><\/a>50] Malgr\u00e9 l&#8217;importance et la fiabilit\u00e9 des \u00e9l\u00e9ments saisis, la gravit\u00e9 des violations des droits garantis par la <i><a class=\"reflex2-link\" href=\"https:\/\/www.canlii.org\/fr\/ca\/legis\/lois\/annexe-b-de-la-loi-de-1982-sur-le-canada-r-u-1982-c-11\/derniere\/annexe-b-de-la-loi-de-1982-sur-le-canada-r-u-1982-c-11.html\">Charte<\/a><\/i>, l&#8217;incidence de telles violations <strong>et le risque r\u00e9el que de telles violations se r\u00e9p\u00e8tent, pour des raisons d\u2019ordre administratif au surplus, justifient d&#8217;exclure la preuve<\/strong>.<\/p>\n<\/div>\n<div class=\"paragWrapper\">\n<p class=\"Paragraphe\" style=\"text-align: justify;\" data-viibes-parag=\"51\" data-viibes-start=\"50\" data-viibes-end=\"49\">[<a class=\"reflex-paragAnchor\" name=\"par51\"><\/a>51] Par ailleurs, puisque les \u00e9l\u00e9ments de preuve exclus constituaient l&#8217;essentiel de la preuve au soutien des accusations port\u00e9es contre le requ\u00e9rant, il y a lieu d&#8217;inscrire un verdict d&#8217;acquittement plut\u00f4t que d&#8217;ordonner un nouveau proc\u00e8s.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Martinbeault c. R., 2022 QCCA 902 Malgr\u00e9 l&#8217;importance et la fiabilit\u00e9 des \u00e9l\u00e9ments saisis, la gravit\u00e9 des violations des droits garantis par la Charte, l&#8217;incidence de telles violations et le risque r\u00e9el que de telles violations se r\u00e9p\u00e8tent, pour des raisons d\u2019ordre administratif au surplus, justifient d&#8217;exclure la preuve. [9] Le juge de premi\u00e8re instance [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"yst_prominent_words":[804,669],"acf":[],"_links":{"self":[{"href":"https:\/\/www.doyonavocats.ca\/en\/wp-json\/wp\/v2\/posts\/17627"}],"collection":[{"href":"https:\/\/www.doyonavocats.ca\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.doyonavocats.ca\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.doyonavocats.ca\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.doyonavocats.ca\/en\/wp-json\/wp\/v2\/comments?post=17627"}],"version-history":[{"count":0,"href":"https:\/\/www.doyonavocats.ca\/en\/wp-json\/wp\/v2\/posts\/17627\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.doyonavocats.ca\/en\/wp-json\/wp\/v2\/media?parent=17627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.doyonavocats.ca\/en\/wp-json\/wp\/v2\/categories?post=17627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.doyonavocats.ca\/en\/wp-json\/wp\/v2\/tags?post=17627"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.doyonavocats.ca\/en\/wp-json\/wp\/v2\/yst_prominent_words?post=17627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}